{"id":1737,"count":1,"description":"","link":"http:\/\/dawnholdingcompanyllc.com\/index.php\/category\/raya-nl-review\/","name":"raya_NL review","slug":"raya-nl-review","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/dawnholdingcompanyllc.com\/index.php\/wp-json\/wp\/v2\/categories\/1737"}],"collection":[{"href":"http:\/\/dawnholdingcompanyllc.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/dawnholdingcompanyllc.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/dawnholdingcompanyllc.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}